{"id":8713,"date":"2023-02-07T09:02:26","date_gmt":"2023-02-07T09:02:26","guid":{"rendered":"https:\/\/sinofudegroup.com\/?p=8713"},"modified":"2023-02-28T08:34:22","modified_gmt":"2023-02-28T08:34:22","slug":"where-does-jelly-candy-come-from","status":"publish","type":"post","link":"https:\/\/sinofudegroup.com\/fr\/dou-viennent-les-bonbons-a-la-gelee\/","title":{"rendered":"D&#039;o\u00f9 viennent les bonbons \u00e0 la gel\u00e9e ?"},"content":{"rendered":"<h2>introduction<\/h2>\n<p><img decoding=\"async\" title=\"machine \u00e0 gommes-bonbons-1-1503\" src=\"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1503.jpg\" alt=\"machine \u00e0 gommes-bonbons-1-1503\"><\/p>\n<p>Les bonbons \u00e0 la gel\u00e9e sont un type de friandise sucr\u00e9e appr\u00e9ci\u00e9e des enfants et des adultes. C\u2019est un d\u00e9lice moelleux, color\u00e9 et souvent au go\u00fbt vif, appr\u00e9ci\u00e9 dans le monde entier. Mais qu\u2019est-ce que la gel\u00e9e de bonbons exactement et comment est-elle n\u00e9e ? Plongeons dans l&#039;histoire de cette friandise sp\u00e9ciale et explorons ses origines.<\/p>\n<h3>D\u00e9finition de Jelly Candy<\/h3>\n<p>Le bonbon \u00e0 la gel\u00e9e est une confiserie \u00e0 base de g\u00e9latine, de sucre et d&#039;ar\u00f4mes. Il est g\u00e9n\u00e9ralement de couleur vive et de texture moelleuse. Souvent, les bonbons \u00e0 la gel\u00e9e se pr\u00e9sentent sous la forme de petits morceaux ronds de la taille d&#039;une bouch\u00e9e, aromatis\u00e9s avec divers ar\u00f4mes naturels ou artificiels. Il est populaire aux \u00c9tats-Unis, au Royaume-Uni, en Australie, en Afrique du Sud et en Nouvelle-Z\u00e9lande. Les parfums les plus appr\u00e9ci\u00e9s sont la framboise, la fraise, le cassis, la poire et le citron.<\/p>\n<h3>Origines historiques de Jelly Candy<\/h3>\n<p>Les bonbons \u00e0 la gel\u00e9e existent depuis des si\u00e8cles. Ses premi\u00e8res origines remontent \u00e0 la Gr\u00e8ce antique, o\u00f9 un confiseur de l&#039;\u00eele de Lesbos fabriquait des bonbons \u00e0 la gel\u00e9e en utilisant un m\u00e9lange de miel, de vin et de g\u00e9latine. Cette friandise \u00e9tait connue sous le nom de \u00ab mazepon \u00bb.<\/p>\n<p>On pense que la forme moderne de bonbon \u00e0 la gel\u00e9e est n\u00e9e au d\u00e9but du 19e si\u00e8cle aux \u00c9tats-Unis. Le premier bonbon commercial \u00e0 la gel\u00e9e a \u00e9t\u00e9 brevet\u00e9 en 1869 par Henry Heide, un immigrant allemand install\u00e9 \u00e0 New York. Le \u00ab Jell-A-Candy \u00bb de Heide \u00e9tait fabriqu\u00e9 \u00e0 partir de sucre et de sirop de ma\u00efs et aromatis\u00e9 \u00e0 l&#039;huile de citron. Cette premi\u00e8re version du bonbon \u00e0 la gel\u00e9e \u00e9tait tr\u00e8s diff\u00e9rente de ce que nous connaissons aujourd&#039;hui, car il s&#039;agissait d&#039;un bonbon dur et cassant.<\/p>\n<p>Au d\u00e9but des ann\u00e9es 1900, les bonbons \u00e0 la gel\u00e9e ont commenc\u00e9 \u00e0 prendre la forme que nous connaissons aujourd\u2019hui. Le processus de fabrication des bonbons \u00e0 la gel\u00e9e a \u00e9t\u00e9 am\u00e9lior\u00e9 en ajoutant de la pectine, ce qui a permis aux bonbons de devenir plus doux et plus moelleux. Ce bonbon \u00e0 la gel\u00e9e est devenu un \u00e9norme succ\u00e8s et s&#039;est rapidement r\u00e9pandu au Royaume-Uni et dans d&#039;autres pays du monde.<\/p>\n<p>Aujourd\u2019hui, les bonbons \u00e0 la gel\u00e9e sont appr\u00e9ci\u00e9s sous de nombreuses formes et vari\u00e9t\u00e9s. Il est largement disponible dans les supermarch\u00e9s et les d\u00e9panneurs du monde entier. Il est \u00e9galement populaire dans divers desserts, tels que les tartes \u00e0 la gel\u00e9e, les rouleaux de gel\u00e9e et les beignets \u00e0 la gel\u00e9e.<\/p>\n<h3>Conclusion<\/h3>\n<p>Les bonbons \u00e0 la gel\u00e9e existent depuis des si\u00e8cles et leur popularit\u00e9 ne cesse de cro\u00eetre. C&#039;est une friandise tr\u00e8s appr\u00e9ci\u00e9e des enfants et des adultes. Avec ses couleurs vives et ses saveurs sucr\u00e9es, les bonbons \u00e0 la gel\u00e9e raviront s\u00fbrement tous ceux qui en prennent une bouch\u00e9e.<\/p>\n<h2>production traditionnelle de bonbons \u00e0 la gel\u00e9e<\/h2>\n<p><img decoding=\"async\" title=\"machine \u00e0 gommes-bonbons-1-1504\" src=\"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1504.jpg\" alt=\"machine \u00e0 gommes-bonbons-1-1504\"><\/p>\n<p>La production de bonbons \u00e0 la gel\u00e9e traditionnels est un processus complexe qui n\u00e9cessite beaucoup de soin et de pr\u00e9cision. De la s\u00e9lection des mati\u00e8res premi\u00e8res \u00e0 l&#039;emballage final, chaque \u00e9tape du processus de production doit \u00eatre \u00e9troitement surveill\u00e9e pour garantir un produit de la plus haute qualit\u00e9. Le r\u00e9sultat est une d\u00e9licieuse g\u00e2terie moelleuse qui est appr\u00e9ci\u00e9e par les adultes et les enfants depuis des si\u00e8cles.<\/p>\n<p>Les bonbons \u00e0 la gel\u00e9e traditionnels sont fabriqu\u00e9s \u00e0 partir de sucre, de g\u00e9latine, de sirop de ma\u00efs et de divers ar\u00f4mes. La g\u00e9latine et le sirop de ma\u00efs sont m\u00e9lang\u00e9s pour former une p\u00e2te \u00e9paisse qui est ensuite chauff\u00e9e \u00e0 une temp\u00e9rature pr\u00e9cise. Une fois que le m\u00e9lange a atteint la bonne temp\u00e9rature, les autres ingr\u00e9dients sont ajout\u00e9s et vers\u00e9s dans des moules. Les moules sont ensuite refroidis et les bonbons g\u00e9lifi\u00e9s sont pr\u00eats \u00e0 \u00eatre emball\u00e9s.<\/p>\n<h3>Production en usine de bonbons \u00e0 la gel\u00e9e<\/h3>\n<p>Lorsqu\u2019il s\u2019agit de produire des bonbons \u00e0 la gel\u00e9e traditionnels en usine, quelques \u00e9tapes essentielles doivent \u00eatre suivies. La premi\u00e8re \u00e9tape est la s\u00e9lection des mati\u00e8res premi\u00e8res. La qualit\u00e9 des mati\u00e8res premi\u00e8res est de la plus haute importance car elle affectera directement le produit fini. Les fournisseurs commerciaux doivent \u00eatre soigneusement s\u00e9lectionn\u00e9s pour garantir que les ingr\u00e9dients utilis\u00e9s sont de la plus haute qualit\u00e9.<\/p>\n<div class=\"internal-linking-related-contents-pro\"><a href=\"https:\/\/sinofudegroup.com\/fr\/ou-a-ete-faite-la-premiere-gelee\/\" class=\"template-7\"><div class=\"postTitle\"><span class=\"ilrcp-title\">O\u00f9 a \u00e9t\u00e9 fabriqu\u00e9e la premi\u00e8re gel\u00e9e ?<\/span><span class=\"ilrcp-author\">\u00c9crit par sinofudetech<br><\/span><span class=\"ilrcp-date\">7 f\u00e9vrier 2023<\/span><\/div><img width=\"250\" height=\"167\" src=\"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1611.jpg\" class=\"alignleft wp-post-image\" alt=\"bonbons-gomme-1-1611\" srcset=\"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1611.jpg 600w, https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1611-300x200.jpg 300w, https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1611-18x12.jpg 18w, https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1611-250x167.jpg 250w\" sizes=\"(max-width: 250px) 100vw, 250px\"><\/a><\/div><p>Une fois les mati\u00e8res premi\u00e8res s\u00e9lectionn\u00e9es, le processus de fabrication peut commencer. La g\u00e9latine et le sirop de ma\u00efs sont m\u00e9lang\u00e9s et chauff\u00e9s \u00e0 la bonne temp\u00e9rature. Une fois que le m\u00e9lange a atteint la bonne temp\u00e9rature, les autres ingr\u00e9dients sont ajout\u00e9s et vers\u00e9s dans des moules. Les moules sont ensuite refroidis et les bonbons g\u00e9lifi\u00e9s sont pr\u00eats \u00e0 \u00eatre emball\u00e9s.<\/p>\n<p>L\u2019emballage est la prochaine \u00e9tape essentielle dans la production en usine de bonbons \u00e0 la gel\u00e9e traditionnels. L&#039;emballage doit \u00eatre con\u00e7u pour conserver la fra\u00eecheur des bonbons et les prot\u00e9ger des dommages potentiels. Le design de l\u2019emballage doit \u00eatre accrocheur et attrayant pour qu\u2019il se d\u00e9marque dans les rayons des magasins. L&#039;emballage doit \u00e9galement contenir des informations nutritionnelles et des avertissements concernant les allerg\u00e8nes, comme l&#039;exige la loi.<\/p>\n<p>La derni\u00e8re \u00e9tape de la production en usine de bonbons \u00e0 la gel\u00e9e traditionnels est le processus d\u2019inspection. Chaque bonbon doit \u00eatre inspect\u00e9 pour sa couleur, sa texture et son go\u00fbt. Toutes les pi\u00e8ces ne r\u00e9pondant pas aux normes de qualit\u00e9 seront retir\u00e9es de la cha\u00eene de production. Une fois les d\u00e9tails inspect\u00e9s, les bonbons sont emball\u00e9s et envoy\u00e9s \u00e0 l\u2019entrep\u00f4t pour distribution.<\/p>\n<p>Les bonbons \u00e0 la gel\u00e9e traditionnels sont un r\u00e9gal appr\u00e9ci\u00e9 depuis des g\u00e9n\u00e9rations. La production de cette d\u00e9licieuse friandise n\u00e9cessite beaucoup de soin et d\u2019attention pour garantir que le r\u00e9sultat soit un produit de haute qualit\u00e9. De la s\u00e9lection des mati\u00e8res premi\u00e8res \u00e0 l\u2019inspection finale, chaque \u00e9tape du processus doit \u00eatre \u00e9troitement surveill\u00e9e pour maintenir les normes de qualit\u00e9 les plus \u00e9lev\u00e9es. Avec les bons ingr\u00e9dients et un \u0153il expert, tous peuvent d\u00e9guster un d\u00e9licieux lot de bonbons \u00e0 la gel\u00e9e traditionnels.<\/p>\n<h2>origines r\u00e9gionales des bonbons \u00e0 la gel\u00e9e<\/h2>\n<p><img decoding=\"async\" title=\"machine \u00e0 gommes-bonbons-1-1505\" src=\"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1505.jpg\" alt=\"machine \u00e0 gommes-bonbons-1-1505\"><\/p>\n<p>Les origines r\u00e9gionales des bonbons \u00e0 la gel\u00e9e remontent \u00e0 l\u2019Europe, \u00e0 l\u2019Asie et \u00e0 l\u2019Am\u00e9rique du Nord. Depuis des si\u00e8cles, les gens du monde entier appr\u00e9cient la saveur, la texture et les couleurs uniques des bonbons g\u00e9lifi\u00e9s. Dans ce blog, nous explorerons les origines r\u00e9gionales des bonbons \u00e0 la gel\u00e9e et comment ces r\u00e9gions ont contribu\u00e9 \u00e0 la friandise bien-aim\u00e9e que nous connaissons et aimons aujourd&#039;hui.<\/p>\n<p>L&#039;Europe est le berceau des bonbons \u00e0 la gel\u00e9e. Au Moyen \u00c2ge, les Europ\u00e9ens \u00e9taient connus pour leurs recettes de confiserie cr\u00e9atives, et les bonbons \u00e0 la gel\u00e9e \u00e9taient l&#039;une de leurs cr\u00e9ations les plus c\u00e9l\u00e8bres. Ils produisaient ces friandises \u00e0 partir de fruits et de jus de fruits, notamment de pommes, d&#039;oranges et de citrons. Cela donnait \u00e0 leurs bonbons \u00e0 la gel\u00e9e une saveur unique, ce qui en faisait un favori de la royaut\u00e9 et des classes sup\u00e9rieures.<\/p>\n<p>En Asie, les bonbons \u00e0 la gel\u00e9e sont produits depuis des si\u00e8cles. Les Chinois ont \u00e9t\u00e9 parmi les premiers \u00e0 d\u00e9velopper des recettes de bonbons g\u00e9lifi\u00e9s, utilisant divers fruits tels que des pommes, des oranges, des ananas et des raisins. Les bonbons chinois \u00e0 la gel\u00e9e \u00e9taient souvent aromatis\u00e9s au gingembre, au miel et aux \u00e9pices. Les Chinois ont \u00e9galement cr\u00e9\u00e9 des formes uniques pour les bonbons, comme des animaux, des \u00e9toiles et d&#039;autres figures.<\/p>\n<p>En Am\u00e9rique du Nord, les bonbons \u00e0 la gel\u00e9e trouvent leurs racines au d\u00e9but des ann\u00e9es 1800. Les pionniers et les colons du continent ont apport\u00e9 avec eux des recettes de bonbons \u00e0 la gel\u00e9e, qu&#039;ils ont modifi\u00e9es selon leurs go\u00fbts. \u00c0 la fin des ann\u00e9es 1800, la production commerciale de bonbons g\u00e9lifi\u00e9s a commenc\u00e9, avec des soci\u00e9t\u00e9s comme Jell-O Company produisant une vari\u00e9t\u00e9 de saveurs et de formes. Aujourd&#039;hui, les bonbons \u00e0 la gel\u00e9e sont une friandise populaire aux \u00c9tats-Unis et au Canada, o\u00f9 les gens de tous \u00e2ges en profitent.<\/p>\n<p>Les origines r\u00e9gionales des bonbons \u00e0 la gel\u00e9e ont contribu\u00e9 \u00e0 donner \u00e0 cette friandise ce qu\u2019elle est aujourd\u2019hui. Les recettes europ\u00e9ennes donnaient au bonbon une saveur unique, tandis que les recettes asiatiques lui donnaient ses formes c\u00e9l\u00e8bres. En Am\u00e9rique du Nord, la production commerciale a contribu\u00e9 \u00e0 faire des bonbons \u00e0 la gel\u00e9e un favori de tous \u00e2ges. Peu importe d\u2019o\u00f9 vous venez, vous pouvez profiter du d\u00e9licieux go\u00fbt des bonbons \u00e0 la gel\u00e9e\u00a0!<\/p>\n<h2>production moderne de bonbons \u00e0 la gel\u00e9e<\/h2>\n<p><img decoding=\"async\" title=\"machine \u00e0 gommes-bonbons-1-1506\" src=\"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1506.jpg\" alt=\"machine \u00e0 gommes-bonbons-1-1506\"><\/p>\n<p>Les bonbons \u00e0 la gel\u00e9e sont l\u2019une des friandises les plus appr\u00e9ci\u00e9es et les plus reconnaissables. Sa texture douce, ses couleurs vives et ses formes uniques en font un incontournable des enfances du monde entier. La production moderne de bonbons g\u00e9lifi\u00e9s est devenue une industrie mondialis\u00e9e et hautement automatis\u00e9e ces derni\u00e8res ann\u00e9es. L\u2019industrie moderne des bonbons \u00e0 la gel\u00e9e a connu plusieurs changements et progr\u00e8s gr\u00e2ce \u00e0 de nouvelles m\u00e9thodes de production et \u00e0 des ingr\u00e9dients artificiels.<\/p>\n<div class=\"internal-linking-related-contents-pro\"><a href=\"https:\/\/sinofudegroup.com\/fr\/comment-faire-vos-propres-bonbons-aux-fruits-en-gelee\/\" class=\"template-7\"><div class=\"postTitle\"><span class=\"ilrcp-title\">Comment faire vos propres bonbons aux fruits en gel\u00e9e ?<\/span><span class=\"ilrcp-author\">\u00c9crit par sinofudetech<br><\/span><span class=\"ilrcp-date\">7 f\u00e9vrier 2023<\/span><\/div><img width=\"250\" height=\"167\" src=\"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/01\/gummy-bear-67.jpg\" class=\"alignleft wp-post-image\" alt=\"gommeux-ours-67\" srcset=\"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/01\/gummy-bear-67.jpg 600w, https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/01\/gummy-bear-67-300x200.jpg 300w, https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/01\/gummy-bear-67-18x12.jpg 18w\" sizes=\"(max-width: 250px) 100vw, 250px\"><\/a><\/div><p>La mondialisation de la production de bonbons g\u00e9lifi\u00e9s a \u00e9t\u00e9 un important moteur d\u2019innovation industrielle. \u00c0 mesure que de plus en plus d\u2019entreprises s\u2019approvisionnent en pays porteurs d\u2019innovation industrielle, elles peuvent cr\u00e9er de nouvelles saveurs et de nouveaux produits sans mod\u00e8le de production localis\u00e9. Cette mondialisation de la production a \u00e9galement permis aux entreprises de r\u00e9duire leurs co\u00fbts, leur permettant ainsi de proposer aux consommateurs des produits plus abordables.<\/p>\n<p>Les ingr\u00e9dients artificiels sont \u00e9galement devenus de plus en plus courants dans l\u2019industrie moderne des bonbons \u00e0 la gel\u00e9e. Des ar\u00f4mes et des colorants artificiels sont utilis\u00e9s pour assurer une plus grande coh\u00e9rence et fiabilit\u00e9 \u00e0 leurs produits. En utilisant des ingr\u00e9dients synth\u00e9tiques, les entreprises peuvent r\u00e9duire leur d\u00e9pendance aux ressources naturelles et cr\u00e9er un produit plus fiable pr\u00e9sentant moins de risques potentiels.<\/p>\n<p>La production de bonbons \u00e0 la gel\u00e9e est un processus hautement sp\u00e9cialis\u00e9 qui n\u00e9cessite beaucoup de comp\u00e9tences et d&#039;expertise. Les entreprises doivent bien comprendre le processus de production, depuis la s\u00e9lection des ingr\u00e9dients jusqu&#039;au stockage et \u00e0 la manipulation appropri\u00e9s du produit fini. Ces connaissances sont essentielles aux entreprises pour garantir que leurs produits r\u00e9pondent aux normes de qualit\u00e9 et peuvent r\u00e9sister aux rigueurs du march\u00e9.<\/p>\n<p>L\u2019industrie moderne des bonbons \u00e0 la gel\u00e9e a \u00e9galement connu plusieurs avanc\u00e9es technologiques. Les entreprises peuvent cr\u00e9er des produits plus efficaces et plus rentables, depuis les lignes de production automatis\u00e9es jusqu&#039;au d\u00e9veloppement d&#039;emballages et d&#039;\u00e9tiquetage sp\u00e9cialis\u00e9s. En tirant parti de la technologie, les entreprises peuvent am\u00e9liorer la qualit\u00e9 de leurs produits et r\u00e9duire le temps et l&#039;\u00e9nergie consacr\u00e9s au processus de production.<\/p>\n<p>En conclusion, l\u2019industrie moderne des bonbons \u00e0 la gel\u00e9e a connu plusieurs changements et progr\u00e8s ces derni\u00e8res ann\u00e9es. De la mondialisation de la production \u00e0 l\u2019utilisation d\u2019ingr\u00e9dients artificiels, les entreprises ont cr\u00e9\u00e9 des produits plus abordables, fiables et efficaces. En tirant parti de la technologie et en utilisant l\u2019expertise d\u2019un personnel qualifi\u00e9, les entreprises peuvent rester comp\u00e9titives et offrir aux consommateurs une grande vari\u00e9t\u00e9 de d\u00e9licieuses friandises.<\/p>\n<h2>conclusion<\/h2>\n<p><img decoding=\"async\" title=\"machine \u00e0 gommes-bonbons-1-1507\" src=\"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1507.jpg\" alt=\"machine \u00e0 gommes-bonbons-1-1507\"><\/p>\n<p>Les bonbons \u00e0 la gel\u00e9e sont une friandise appr\u00e9ci\u00e9e des personnes de tous \u00e2ges. Ses origines remontent aux anciens Grecs et Romains, mais c&#039;est au Moyen \u00c2ge que ces friandises sont devenues un aliment de base dans l&#039;alimentation de nombreux Europ\u00e9ens. \u00c0 partir du XVIIIe si\u00e8cle, les bonbons \u00e0 la gel\u00e9e sont devenus de plus en plus populaires et les m\u00e9thodes de production ont \u00e9volu\u00e9 pour r\u00e9pondre \u00e0 la demande.<\/p>\n<p>Aujourd&#039;hui, les bonbons \u00e0 la gel\u00e9e sont appr\u00e9ci\u00e9s partout dans le monde et sont disponibles dans une vari\u00e9t\u00e9 de formes, de couleurs et de saveurs. Les m\u00e9thodes de production modernes ont permis aux fabricants de produire ces friandises en grande quantit\u00e9 et \u00e0 des co\u00fbts bien inf\u00e9rieurs, les rendant ainsi accessibles et abordables.<\/p>\n<p>Les origines des bonbons \u00e0 la gel\u00e9e sont ancr\u00e9es dans l\u2019histoire et leur popularit\u00e9 n\u2019a cess\u00e9 de cro\u00eetre. Sa production a \u00e9galement \u00e9volu\u00e9 pour r\u00e9pondre \u00e0 la demande, avec des m\u00e9thodes de production modernes permettant de cr\u00e9er de plus grandes quantit\u00e9s \u00e0 moindre co\u00fbt. Le r\u00e9sultat est un r\u00e9gal appr\u00e9ci\u00e9 des personnes de tous \u00e2ges.<\/p>\n<p>L\u2019impact des m\u00e9thodes de production modernes a \u00e9t\u00e9 immense. En tirant parti des progr\u00e8s technologiques, les fabricants peuvent produire des bonbons g\u00e9lifi\u00e9s en grande quantit\u00e9 et \u00e0 moindre co\u00fbt, rendant ainsi le traitement accessible et abordable. Cela a permis aux bonbons \u00e0 la gel\u00e9e de devenir un aliment de base dans l\u2019alimentation de nombreuses personnes \u00e0 travers le monde.<\/p>\n<p>En conclusion, les bonbons \u00e0 la gel\u00e9e ont parcouru un long chemin depuis leurs origines dans la Gr\u00e8ce antique et \u00e0 Rome. Sa popularit\u00e9 n\u2019a cess\u00e9 de cro\u00eetre au fil du temps et les m\u00e9thodes de production modernes ont permis de cr\u00e9er de plus grandes quantit\u00e9s \u00e0 moindre co\u00fbt, le rendant ainsi accessible et abordable pour tous. Les bonbons \u00e0 la gel\u00e9e sont d\u00e9sormais appr\u00e9ci\u00e9s dans le monde entier et constituent un r\u00e9gal appr\u00e9ci\u00e9 des personnes de tous \u00e2ges.<\/p>\n<h3><span style=\"color: #008000;\"><em><strong>Obtenez la solution compl\u00e8te. \u2193<\/strong><\/em><\/span><\/h3>\n<blockquote class=\"wp-embedded-content\" data-secret=\"4Gy5VQkDkn\"><p><a href=\"https:\/\/sinofudegroup.com\/fr\/le-guide-ultime-de-la-chaine-de-production-de-bonbons-a-la-gelee\/\" target=\"_blank\">Le guide ultime de la cha\u00eene de production de bonbons \u00e0 la gel\u00e9e<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abLe guide ultime de la cha\u00eene de production de bonbons \u00e0 la gel\u00e9e\u00bb - Sinofude\" src=\"https:\/\/sinofudegroup.com\/the-ultimate-guide-to-jelly-candy-production-line\/embed\/#?secret=qduRr5C5ot#?secret=4Gy5VQkDkn\" data-secret=\"4Gy5VQkDkn\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>introduction Jelly candy is a type of sweet treat that is beloved by children and adults alike. It is a chewy, colorful, and often brightly flavored joy enjoyed worldwide. But what is jelly candy exactly, and how did it come to be? Let&rsquo;s delve into the history of this special treat and explore its origins. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[39],"tags":[],"class_list":["post-8713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guide-to-jelly-candy-production-line"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.4 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Where does jelly candy come from? - Sinofude<\/title>\n<meta name=\"description\" content=\"Its production has also evolved to match demand, with modern production methods allowing larger quantities to be created at lower costs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sinofudegroup.com\/fr\/dou-viennent-les-bonbons-a-la-gelee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Where does jelly candy come from?\" \/>\n<meta property=\"og:description\" content=\"Its production has also evolved to match demand, with modern production methods allowing larger quantities to be created at lower costs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinofudegroup.com\/fr\/dou-viennent-les-bonbons-a-la-gelee\/\" \/>\n<meta property=\"og:site_name\" content=\"Sinofude\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100086326506584\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-07T09:02:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-28T08:34:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1679.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sinofudetech\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SINOFUDE888\" \/>\n<meta name=\"twitter:site\" content=\"@SINOFUDE888\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"sinofudetech\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/\"},\"author\":{\"name\":\"sinofudetech\",\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/#\\\/schema\\\/person\\\/7e41349b2a9266349ce07db72ae1dd5e\"},\"headline\":\"Where does jelly candy come from?\",\"datePublished\":\"2023-02-07T09:02:26+00:00\",\"dateModified\":\"2023-02-28T08:34:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/\"},\"wordCount\":1769,\"publisher\":{\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sinofudegroup.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/gummy-candy-1-1679.jpg\",\"articleSection\":[\"Guide to Jelly Candy Production Line\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/\",\"url\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/\",\"name\":\"Where does jelly candy come from? - Sinofude\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sinofudegroup.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/gummy-candy-1-1679.jpg\",\"datePublished\":\"2023-02-07T09:02:26+00:00\",\"dateModified\":\"2023-02-28T08:34:22+00:00\",\"description\":\"Its production has also evolved to match demand, with modern production methods allowing larger quantities to be created at lower costs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sinofudegroup.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/gummy-candy-1-1679.jpg\",\"contentUrl\":\"https:\\\/\\\/sinofudegroup.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/gummy-candy-1-1679.jpg\",\"width\":600,\"height\":400,\"caption\":\"gummy-candy-1-1679\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/where-does-jelly-candy-come-from\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sinofudegroup.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Where does jelly candy come from?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/#website\",\"url\":\"https:\\\/\\\/sinofudegroup.com\\\/\",\"name\":\"Sinofude\",\"description\":\"Top gummy making machine manufacturer in China\",\"publisher\":{\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sinofudegroup.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/#organization\",\"name\":\"Sinofude\",\"url\":\"https:\\\/\\\/sinofudegroup.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sinofudegroup.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/\u6625\u742aLOGO.png\",\"contentUrl\":\"https:\\\/\\\/sinofudegroup.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/\u6625\u742aLOGO.png\",\"width\":180,\"height\":60,\"caption\":\"Sinofude\"},\"image\":{\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100086326506584\",\"https:\\\/\\\/x.com\\\/SINOFUDE888\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeA_f3ra6gWO96R97N8XA0A\",\"https:\\\/\\\/www.instagram.com\\\/sinofude668\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/89696970\\\/admin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sinofudegroup.com\\\/#\\\/schema\\\/person\\\/7e41349b2a9266349ce07db72ae1dd5e\",\"name\":\"sinofudetech\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g\",\"caption\":\"sinofudetech\"},\"sameAs\":[\"https:\\\/\\\/sinofudegroup.com\"],\"url\":\"https:\\\/\\\/sinofudegroup.com\\\/fr\\\/author\\\/sinofudetech\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D&#039;o\u00f9 viennent les bonbons \u00e0 la gel\u00e9e ? - Sinofude","description":"Sa production a \u00e9galement \u00e9volu\u00e9 pour r\u00e9pondre \u00e0 la demande, avec des m\u00e9thodes de production modernes permettant de cr\u00e9er de plus grandes quantit\u00e9s \u00e0 moindre co\u00fbt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sinofudegroup.com\/fr\/dou-viennent-les-bonbons-a-la-gelee\/","og_locale":"fr_CA","og_type":"article","og_title":"Where does jelly candy come from?","og_description":"Its production has also evolved to match demand, with modern production methods allowing larger quantities to be created at lower costs.","og_url":"https:\/\/sinofudegroup.com\/fr\/dou-viennent-les-bonbons-a-la-gelee\/","og_site_name":"Sinofude","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100086326506584","article_published_time":"2023-02-07T09:02:26+00:00","article_modified_time":"2023-02-28T08:34:22+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1679.jpg","type":"image\/jpeg"}],"author":"sinofudetech","twitter_card":"summary_large_image","twitter_creator":"@SINOFUDE888","twitter_site":"@SINOFUDE888","twitter_misc":{"\u00c9crit par":"sinofudetech","Estimation du temps de lecture":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/#article","isPartOf":{"@id":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/"},"author":{"name":"sinofudetech","@id":"https:\/\/sinofudegroup.com\/#\/schema\/person\/7e41349b2a9266349ce07db72ae1dd5e"},"headline":"Where does jelly candy come from?","datePublished":"2023-02-07T09:02:26+00:00","dateModified":"2023-02-28T08:34:22+00:00","mainEntityOfPage":{"@id":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/"},"wordCount":1769,"publisher":{"@id":"https:\/\/sinofudegroup.com\/#organization"},"image":{"@id":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/#primaryimage"},"thumbnailUrl":"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1679.jpg","articleSection":["Guide to Jelly Candy Production Line"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/","url":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/","name":"D&#039;o\u00f9 viennent les bonbons \u00e0 la gel\u00e9e ? - Sinofude","isPartOf":{"@id":"https:\/\/sinofudegroup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/#primaryimage"},"image":{"@id":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/#primaryimage"},"thumbnailUrl":"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1679.jpg","datePublished":"2023-02-07T09:02:26+00:00","dateModified":"2023-02-28T08:34:22+00:00","description":"Sa production a \u00e9galement \u00e9volu\u00e9 pour r\u00e9pondre \u00e0 la demande, avec des m\u00e9thodes de production modernes permettant de cr\u00e9er de plus grandes quantit\u00e9s \u00e0 moindre co\u00fbt.","breadcrumb":{"@id":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/#primaryimage","url":"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1679.jpg","contentUrl":"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2023\/02\/gummy-candy-1-1679.jpg","width":600,"height":400,"caption":"gummy-candy-1-1679"},{"@type":"BreadcrumbList","@id":"https:\/\/sinofudegroup.com\/where-does-jelly-candy-come-from\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sinofudegroup.com\/"},{"@type":"ListItem","position":2,"name":"Where does jelly candy come from?"}]},{"@type":"WebSite","@id":"https:\/\/sinofudegroup.com\/#website","url":"https:\/\/sinofudegroup.com\/","name":"Sinofude","description":"Premier fabricant de machines de fabrication de gommes en Chine","publisher":{"@id":"https:\/\/sinofudegroup.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinofudegroup.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/sinofudegroup.com\/#organization","name":"Sinofude","url":"https:\/\/sinofudegroup.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/sinofudegroup.com\/#\/schema\/logo\/image\/","url":"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2022\/12\/\u6625\u742aLOGO.png","contentUrl":"https:\/\/sinofudegroup.com\/wp-content\/uploads\/2022\/12\/\u6625\u742aLOGO.png","width":180,"height":60,"caption":"Sinofude"},"image":{"@id":"https:\/\/sinofudegroup.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100086326506584","https:\/\/x.com\/SINOFUDE888","https:\/\/www.youtube.com\/channel\/UCeA_f3ra6gWO96R97N8XA0A","https:\/\/www.instagram.com\/sinofude668\/","https:\/\/www.linkedin.com\/company\/89696970\/admin\/"]},{"@type":"Person","@id":"https:\/\/sinofudegroup.com\/#\/schema\/person\/7e41349b2a9266349ce07db72ae1dd5e","name":"sinofudetech","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a9bdb892d57e70c0de6902869137644fd47304144ff8732d63e81ee5b572348?s=96&d=mm&r=g","caption":"sinofudetech"},"sameAs":["https:\/\/sinofudegroup.com"],"url":"https:\/\/sinofudegroup.com\/fr\/author\/sinofudetech\/"}]}},"_links":{"self":[{"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/posts\/8713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/comments?post=8713"}],"version-history":[{"count":2,"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/posts\/8713\/revisions"}],"predecessor-version":[{"id":8961,"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/posts\/8713\/revisions\/8961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/media\/8500"}],"wp:attachment":[{"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/media?parent=8713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/categories?post=8713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sinofudegroup.com\/fr\/wp-json\/wp\/v2\/tags?post=8713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}